{"id":17709,"date":"2023-06-21T00:00:56","date_gmt":"2023-06-20T22:00:56","guid":{"rendered":"https:\/\/gerd-kommer.de\/blog\/the-etf-by-gerd-kommer\/"},"modified":"2025-12-17T13:06:54","modified_gmt":"2025-12-17T12:06:54","slug":"etf-di-gerd-kommer","status":"publish","type":"post","link":"https:\/\/gerd-kommer.de\/it\/blog\/etf-di-gerd-kommer\/","title":{"rendered":"L&#8217;ETF di Gerd Kommer"},"content":{"rendered":"<p><em>Di <a href=\"https:\/\/gerd-kommer.de\/it\/team\/daniel-kanzler\/\" target=\"_blank\" rel=\"noopener noreferrer\">Daniel Kanzler<\/a> e <a href=\"https:\/\/gerd-kommer.de\/it\/team\/alexander-weis\/\" target=\"_blank\" rel=\"noopener noreferrer\">Alexander Weis<\/a>\u00a0\u00a0<\/em><\/p>\n<p>Chiunque si occupi di ETF nell&#8217;area di lingua tedesca non pu\u00f2 non conoscere una persona in particolare: il Dr. Gerd Kommer. Da 23 anni scrive guide sul tema &#8220;Investimenti con fondi indicizzati ed ETF&#8221; e da 30 anni opera nel settore finanziario. Gerd Kommer ha reso noto nel mercato degli investitori privati dei paesi dell&#8217;area di lingua tedesca l&#8217;investimento senza previsioni e basato su regole fondato su conoscenze scientifiche consolidate, coniando a tal fine il termine &#8220;portafoglio globale&#8221;. Questo approccio d\u2019investimento, realizzabile con gli ETF, \u00e8 diventato sempre pi\u00f9 popolare negli ultimi anni tra gli investitori privati dei paesi di lingua tedesca grazie al suo concetto convincente, al suo rendimento atteso interessante a lungo termine e alla sua facile implementazione, talvolta anche con denominazioni simili come &#8220;Weltdepot&#8221; o &#8220;Welt-AG&#8221; e in forme di implementazione leggermente modificate.<\/p>\n<p>Il portafoglio globale non \u00e8 una combinazione fissa di ETF o indici di titoli specifici, ma un concetto globale coerente che ogni investitore pu\u00f2 adattare in modo flessibile alle proprie circostanze e ai propri obiettivi specifici, quasi come gli iconici coltellini svizzeri rossi di Victorinox. Tuttavia, dal punto di vista di un investitore, questa flessibilit\u00e0 pu\u00f2 anche essere percepita come complessit\u00e0 o maggiore carico di lavoro.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Da giugno 2023 abbiamo una soluzione per gli investitori DIY: l&#8217;<i>L&amp;G Gerd Kommer Multifactor Equity UCITS ETF<\/i>, che in questo articolo del blog chiameremo &#8220;Gerd-Kommer-ETF&#8221; per brevit\u00e0. Di seguito riassumiamo le caratteristiche pi\u00f9 importanti del Gerd-Kommer-ETF.<\/p>\n<p>Questa pubblicazione ha finalit\u00e0 di marketing. Si prega di leggere il prospetto del fondo e le informazioni chiave per gli investitori prima di prendere una decisione d\u2019investimento definitiva.<\/p>\n<p>&nbsp;<\/p>\n<h2><b>1 Caratteristiche di base<\/b><\/h2>\n<p>Il Gerd-Kommer-ETF \u00e8 un ETF azionario puro che tiene traccia della parte di portafoglio rischiosa del concetto di portafoglio globale in un unico fondo, ovvero una &#8220;soluzione 1-ETF&#8221;. Per &#8220;componente rischiosa del portafoglio&#8221; si intende qui il &#8220;mercato azionario globale&#8221;. A nostro avviso, chi desidera investire in una \u201callocazione livello 1 100\/0\u201d fortemente orientata al rendimento (100% a rischio \/ 0% a basso rischio) non ha bisogno di altri ETF oltre al Gerd-Kommer-ETF. Chi desidera adottare un approccio pi\u00f9 conservativo (orientato alla sicurezza), quindi con un\u2019allocazione livello 1 di &#8220;90\/10&#8221;, &#8220;80\/20&#8221;, &#8220;70\/30&#8221; ecc. fino a &#8220;10\/90&#8221;, pu\u00f2 combinare il Gerd-Kommer-ETF con un ETF obbligazionario o coprire la parte a basso rischio del portafoglio con un conto corrente fruttifero presso una banca. L&#8217;ETF obbligazionario utilizzato deve coprire esclusivamente durate residue brevi di debitori con un elevato rating creditizio nella valuta locale dell&#8217;investitore. Per motivi di rischio, il saldo del conto corrente non dovrebbe superare i 100.000 euro, il limite massimo della garanzia sui depositi statale in Germania.<\/p>\n<p>&nbsp;<\/p>\n<h2><b>2 Societ\u00e0 d\u2019investimento (KVG)<\/b><\/h2>\n<p>Il Gerd-Kommer-ETF \u00e8 gestito dal fornitore di ETF <i>Legal &amp; General Investment<\/i> <i>Management (&#8220;L&amp;<\/i> G <em>&#8220;).<\/em> <a href=\"https:\/\/am.landg.com\/it-it\/investitori-privati\/\" target=\"_blank\" rel=\"noopener\">L&amp;G<\/a> fa parte del gruppo britannico Legal &amp; General (&#8220;L&amp;G&#8221;), una delle pi\u00f9 grandi compagnie assicurative in Europa. L&amp;G \u00e8 uno dei principali asset manager (amministratori patrimoniali) del mondo. A dicembre 2022, il patrimonio gestito da L&amp;G ammontava a circa 1.300 miliardi di euro. A met\u00e0 del 2023, L&amp;G offre quasi 50 diversi ETF sul mercato tedesco.<\/p>\n<p>&nbsp;<\/p>\n<h2><b>3 Indice azionario sottostante<\/b><\/h2>\n<p>L&#8217;indice su cui si basa il Gerd-Kommer-ETF \u00e8 stato sviluppato dal Dott. Gerd Kommer e dal suo team in collaborazione con <i>Solactive AG<\/i> e <i>L&amp;G<\/i> negli anni 2022 e 2023. <a href=\"https:\/\/www.solactive.com\/\" target=\"_blank\" rel=\"noopener\">Solactive<\/a> \u00e8 un fornitore di indici tedesco con sede a Francoforte. L&#8217;indice di riferimento su cui si basa l&#8217;indice \u00e8 denominato <i>Solactive GBS Global Markets Investable Universe USD Index NTR<\/i> (ISIN: DE000SL0EM79) e l&#8217;indice su cui si basa il Gerd-Kommer-ETF si chiama <i>Solactive Gerd Kommer Multifactor Equity Index NTR <\/i>(ISIN: DE000SL0G219). <b>[1]<\/b> L&#8217;indice riflette il mercato azionario globale, il &#8220;Welt-AG&#8221;, ed \u00e8 quindi sostanzialmente paragonabile a un ETF azionario sul noto indice MSCI ACWI. Tuttavia, il Gerd-Kommer-ETF si discosta consapevolmente e in modo significativo da un ETF MSCI World in alcuni punti importanti descritti di seguito. <b>[2]<\/b><span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>4 &#8220;Principio All-Cap-All-Market&#8221;<\/b><\/h2>\n<p>A differenza di un ETF MSCI World, il Gerd-Kommer-ETF include anche azioni dei Paesi emergenti nella dimensione <i>regionale<\/i> e small cap (azioni secondarie) nella <i>dimensione<\/i>. Si pu\u00f2 parlare quindi di un &#8220;All Cap All Market ETF&#8221;, che riflette l&#8217;intero mercato azionario mondiale. L&#8217;MSCI World, invece, non tiene conto delle azioni dei Paesi emergenti e delle small cap.<\/p>\n<p>&nbsp;<\/p>\n<h2><b>5 Ponderazione per paese<\/b><\/h2>\n<p>Il Gerd-Kommer-ETF comprende quasi 50 Paesi (rispetto ai 23 dell&#8217;ETF MSCI World [al giugno 2023]). La ponderazione di un singolo Paese nell&#8217;indice \u00e8 determinata per il 50% dalla sua capitalizzazione del mercato e per il 50% dalla quota del Paese nel prodotto interno lordo globale (performance economica globale). In questo modo, ad esempio, il rischio di concentrazione negli Stati Uniti, che vediamo nell&#8217;indice MSCI World (situazione a giugno 2023 con una ponderazione degli USA superiore al 67%), viene notevolmente attenuato. Per contro, i Paesi emergenti e la maggior parte dei Paesi industrializzati non statunitensi hanno una ponderazione pi\u00f9 elevata.<\/p>\n<p>&nbsp;<\/p>\n<h2><b>6 Forma di replica dell&#8217;indice<\/b><\/h2>\n<p>Il Gerd-Kommer-ETF \u00e8 un ETF a replica fisica, ovvero non un ETF su swap (ETF sintetico). Ci\u00f2 garantisce che l&#8217;indice sottostante sia riprodotto nel modo pi\u00f9 fedele possibile e che non sussista alcun rischio di controparte sotto forma di banca. La replica fisica avviene tramite campionamento ottimizzato (Optimized Sampling) al fine di limitare il pi\u00f9 possibile i costi del fondo.<\/p>\n<p>&nbsp;<\/p>\n<h2><b>7 Utilizzo dei dividendi<\/b><\/h2>\n<p>L&#8217;ETF \u00e8 disponibile in una classe di quote a capitalizzazione (ISIN: WELT0A; ISIN: IE0001UQQ933) e in una classe di quote a distribuzione (WKN: WELT0B; ISIN IE000FPWSL69), al fine di soddisfare le diverse esigenze degli investitori.<\/p>\n<p>&nbsp;<\/p>\n<h2><b>8 Factor Investing<\/b><\/h2>\n<p>Il Gerd-Kommer-ETF \u00e8 un <i>ETF multi-fattore<\/i> che sovrapondera i cosiddetti &#8220;premi di fattore&#8221; rispetto a un indice azionario passivo neutrale rispetto al mercato (&#8220;plain vanilla&#8221;). <b>[3]<\/b> Il factor investing \u00e8 noto anche come <i>Smart beta investing<\/i>. I premi di fattore sono caratteristiche delle azioni identificate dalla scienza che hanno una correlazione sistematica e statistica con il rendimento e il rischio e la cui sovraponderazione in un portafoglio azionario dovrebbe generare un rendimento supplementare a lungo termine rispetto a un portafoglio neutrale rispetto al mercato. I premi di fattore rappresentati nel Gerd-Kommer-ETF sono:<\/p>\n<ul>\n<li><b>Size:<\/b> Le azioni di piccole imprese, misurate in base alla capitalizzazione del mercato, hanno un rendimento atteso statisticamente pi\u00f9 elevato rispetto alle azioni di grandi imprese.<\/li>\n<li><b>Value:<\/b> Le azioni il cui prezzo \u00e8 basso rispetto a determinati indicatori aziendali (ad es. utili o patrimonio netto contabile) hanno un rendimento atteso statisticamente pi\u00f9 elevato rispetto ad azioni altrimenti identiche in cui ci\u00f2 non si verifica. In altre parole: le azioni &#8220;economiche&#8221; (azioni Value) hanno un rendimento atteso pi\u00f9 elevato rispetto a quello delle azioni &#8220;costose&#8221; (a valutazione elevata), le cosiddette azioni Growth o di crescita.<\/li>\n<li><b>Quality:<\/b> Le azioni con una redditivit\u00e0 superiore alla media, una crescente rotazione del capitale e\/o un basso livello di indebitamento hanno un rendimento atteso statisticamente pi\u00f9 elevato rispetto ad azioni altrimenti identiche che non presentano queste caratteristiche.<\/li>\n<li><b>Investment: <\/b>Le azioni con una crescita del totale di bilancio contenuta hanno un rendimento atteso statisticamente pi\u00f9 elevato rispetto alle azioni con una crescita del bilancio elevata.<\/li>\n<li><b>Momentum:<\/b> Le azioni che negli ultimi mesi hanno registrato un rendimento superiore alla media hanno per un breve periodo di tempo un rendimento atteso statisticamente pi\u00f9 elevato rispetto alle azioni che hanno registrato un rendimento scarso in quel periodo.<span class=\"Apple-converted-space\">\u00a0<\/span><\/li>\n<li><b>Political Risk:<\/b> Le azioni dei paesi emergenti, particolarmente esposte al &#8220;rischio politico&#8221;, hanno un rendimento atteso statisticamente pi\u00f9 elevato rispetto a quello delle azioni dei Paesi industrializzati.<\/li>\n<\/ul>\n<p>La sovraponderazione di questi premi di fattore ha l&#8217;obiettivo di generare un rendimento supplementare (anche al netto dei costi) rispetto a un ETF neutrale rispetto al mercato nel lungo termine.<\/p>\n<p>Nel caso del Gerd-Kommer-ETF si pu\u00f2 parlare di Multifactor Investing <i>integrato<\/i>, in quanto tutti questi premi di fattore presi in considerazione sono rappresentati in un <i>singolo<\/i> indice anzich\u00e9 in pi\u00f9 indici individuali. In questo modo, teoricamente si riducono le possibili interazioni sfavorevoli tra i singoli premi di fattore. Inoltre, si sfrutta il fatto che determinati premi di fattore hanno un effetto pi\u00f9 forte in combinazione con altri piuttosto che &#8220;da soli&#8221;. Questo vale ad esempio per <i>Size<\/i> e <i>Value<\/i> o <i>Size <\/i>e <i>Quality<\/i>.<\/p>\n<p>Per ottenere un&#8217;ampia diversificazione, i premi di fattore <i>Size<\/i>, <i>Value<\/i> e <i>Quality<\/i> vengono ottenuti adeguando le rispettive ponderazioni delle azioni. Ci\u00f2 avviene nell\u2019ambito del rebalancing trimestrale, in cui i tre fattori vengono considerati in modo equamente ponderato.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Per quanto riguarda i premi <i>Momentum<\/i> e <i>Investment<\/i>, utilizziamo una speciale tecnica di screening per ridurre al minimo la rotazione dei titoli (turnover) associata all\u2019utilizzo di questi due premi e i costi di transazione da esso generati.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Il premio Political Risk deriva dall&#8217;adeguamento delle ponderazioni dei paesi al prodotto interno lordo gi\u00e0 prima dell&#8217;ottimizzazione.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>I premi di fattore sono volatili, ovvero fluttuano nel tempo, proprio come i rendimenti azionari in generale. In altre parole: I premi di fattore non sono permanenti (cio\u00e8 non si verificano ogni mese o ogni anno), ma possono anche trasformarsi da &#8220;bonus&#8221; a &#8220;malus&#8221; su periodi di tempo prolungati. Se i premi di fattore fossero continui (cio\u00e8 &#8220;garantiti&#8221;), sarebbero stati da tempo arbitrati, ovvero resi cos\u00ec &#8220;costosi&#8221; dalla forte domanda da non offrire pi\u00f9 alcun vantaggio di rendimento.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Per i lettori che desiderano approfondire l&#8217;argomento del factor investing, abbiamo scritto questo articolo del blog: <a href=\"https:\/\/gerd-kommer.de\/it\/blog\/factor-investing-le-basi\/\" target=\"_blank\" rel=\"noopener\">&#8220;Factor Investing \u2013 le basi&#8221;<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<h2><b>9 Elevata diversificazione (&#8220;ultradiversificazione&#8221;)<\/b><b>\u00a0<\/b><\/h2>\n<p>Nonostante si tenga conto dei premi di fattore e dei filtri ESG, che tendono a ridurre l&#8217;universo d\u2019investimento, l&#8217;indice comprende circa 5.000 titoli singoli (su circa 10.000 azioni nei segmenti Prime Listing Standard delle borse dei quasi 50 paesi considerati). Da queste circa 5.000 azioni singole, il Gerd-Kommer-ETF seleziona oltre 4.000 titoli singoli mediante un campionamento ottimizzato (procedura optimized sampling). Con l&#8217;aumento del volume del fondo nell&#8217;ETF, questo numero pu\u00f2 aumentare. La ponderazione massima di una singola azione nell&#8217;indice \u00e8 limitata a un valore massimo dell\u2019uno percento in ogni data di adeguamento, in modo da evitare un &#8220;eccesso di ponderazione&#8221; (una quota superiore al 10% delle dieci azioni pi\u00f9 grandi, che esiste in molti altri ETF su indici azionari globali). Grazie allo speciale metodo di ponderazione per paese descritto sopra, si ottiene anche una migliore diversificazione tra i paesi rispetto agli ETF azionari tradizionali.<\/p>\n<p><b>\u00a0<\/b><\/p>\n<h2><b>10 Filtri di sostenibilit\u00e0 leggeri<\/b><\/h2>\n<p>L&#8217;indice Solactive su cui si basa il Gerd-Kommer-ETF include un filtro ecologico (screen) incentrato sulla riduzione delle emissioni di CO<sub>2<\/sub>. A tal fine, viene escluso il 3% delle aziende con le emissioni di CO<sub>2<\/sub> pi\u00f9 elevate negli undici &#8220;settori principali&#8221;. Sono inoltre escluse le aziende che violano le norme delle Nazioni Unite, che commettono le pi\u00f9 gravi violazioni della sostenibilit\u00e0 (&#8220;Severe ESG Controversies&#8221;), che producono armi controverse e i produttori di carbone. <b>[4]<\/b><span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>11 Ulteriori criteri di esclusione specifici delle aziende<\/b><\/h2>\n<p>La ricerca scientifica ha dimostrato che determinati tipi di azioni o costellazioni di azioni presentano combinazioni rischio\/rendimento statisticamente poco attraenti. Tra queste figurano le azioni di societ\u00e0 che hanno effettuato la loro prima offerta pubblica iniziale (IPO\/Initial Public Offering) solo di recente e le azioni per le quali il tasso di prestito titoli \u00e8 molto elevato rispetto al mercato. <b>[5]<\/b><\/p>\n<p>&nbsp;<\/p>\n<h2><b>12 Prestito titoli<\/b><\/h2>\n<p>Al momento (a giugno 2023) il Gerd-Kommer-ETF non effettua prestiti titoli con le azioni contenute nell&#8217;ETF.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>13 Data di ricostituzione dell&#8217;indice e rebalancing<\/b><b>\u00a0<\/b><\/h2>\n<p>Ogni tre mesi vengono ricalcolati i componenti e la loro ponderazione dell&#8217;indice sottostante e le azioni che non soddisfano pi\u00f9 i criteri dell&#8217;indice vengono sostituite con quelle che ora li soddisfano. Laddove gli ulteriori requisiti dell&#8217;indice non sono pi\u00f9 pienamente soddisfatti, questo rebalancing basato su regole garantisce che ci\u00f2 avvenga nuovamente.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>14 Vigilanza e protezione degli investitori<\/b><\/h2>\n<p>Il Gerd-Kommer-ETF \u00e8 un cosiddetto fondo UCITS, ovvero un fondo d&#8217;investimento liberamente autorizzato alla distribuzione agli investitori privati all&#8217;interno dell&#8217;UE. I fondi degli investitori rappresentano un patrimonio speciale, separato dal punto di vista giuridico e infrastrutturale dal patrimonio della societ\u00e0 d\u2019investimento (L&amp;G). Un fallimento della societ\u00e0 d\u2019investimento non avrebbe alcun effetto negativo sui fondi degli investitori. Allo stesso modo, l&#8217;investitore non corre alcun rischio di insolvenza bancaria in relazione al deposito in cui le quote dell&#8217;ETF sono custodite presso la banca dell&#8217;investitore, dal momento che la banca svolge solo il ruolo di depositaria per i valori in deposito (qui c&#8217;\u00e8 un&#8217;importante differenza giuridica rispetto a un conto bancario e a un deposito bancario). Inoltre, si applicano tutti i requisiti normativi in materia di gestione del rischio e protezione degli investitori previsti dalla normativa UCITS.<\/p>\n<p>&nbsp;<\/p>\n<h2><b>15 Costi<\/b><\/h2>\n<p>I costi dell&#8217;ETF (&#8220;TER&#8221;) ammontano allo 0,45% all&#8217;anno, sono gi\u00e0 inclusi nel rendimento dichiarato dell&#8217;ETF e vengono quindi compensati direttamente dal rendimento, ovvero riducono automaticamente l\u2019utile imponibile.<\/p>\n<p>I costi del Gerd-Kommer-ETF sono paragonabili a quelli di altri ETF multi-fattore o fondi del portafoglio e sono drasticamente inferiori a quelli dei fondi attivi convenzionali. \u00c8 possibile un confronto solo parziale con gli ETF, ad esempio quelli sull&#8217;indice MSCI World, dal momento che il Gerd-Kommer-ETF offre molte pi\u00f9 funzionalit\u00e0 ed \u00e8 pi\u00f9 complesso.<\/p>\n<p>Siamo convinti di offrire un prezzo equo per il Gerd-Kommer-ETF, dal momento che oltre a un approccio multi-fattore integrato e a un&#8217;ultradiversificazione, offre una ponderazione per paese innovativa che tiene conto della performance economica, cosa unica in Germania.<\/p>\n<p>&nbsp;<\/p>\n<h2><b>16 Disponibilit\u00e0<\/b><\/h2>\n<p>L\u2019ETF di Gerd Kommer \u00e8 quotato su XETRA dal 21\/06\/2023 ed \u00e8 disponibile presso tutte le principali banche e i broker in Italia.<\/p>\n<p>&nbsp;<\/p>\n<h2><b>17 Idoneit\u00e0 al piano di risparmio<\/b><\/h2>\n<article class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto [content-visibility:auto] supports-[content-visibility:auto]:[contain-intrinsic-size:auto_100lvh] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"request-WEB:90b84b69-b770-413c-bbe8-ca4cc400e7ef-6\" data-testid=\"conversation-turn-14\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:--spacing(4)] thread-sm:[--thread-content-margin:--spacing(6)] thread-lg:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] thread-lg:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"40676183-90ab-4ee3-9a7c-51b605b5971d\" data-message-model-slug=\"gpt-5-1\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[1px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words light markdown-new-styling\">\n<p data-start=\"65\" data-end=\"146\" data-is-last-node=\"\" data-is-only-node=\"\">L\u2019ETF \u00e8 disponibile come piano di accumulo presso la maggior parte dei fornitori.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"z-0 flex min-h-[46px] justify-start\"><\/div>\n<\/div>\n<\/div>\n<\/article>\n<h2><b>18 Importo minimo dell&#8217;investimento<\/b><\/h2>\n<p>Non \u00e8 previsto un importo minimo dell\u2019investimento.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>19 Ulteriori informazioni<\/b><\/h2>\n<p>Ulteriori informazioni di marketing sono disponibili sul sito web dell&#8217;ETF (<a href=\"https:\/\/gerd-kommer.de\/it\/etf\/\">https:\/\/gerd-kommer.de\/it\/etf\/<\/a>). Tutte le informazioni legali, compreso il prospetto del fondo e le informazioni chiave per gli investitori (KID), sono disponibili sul <a href=\"https:\/\/fundcentres.lgim.com\/de\/de\/adviser-wealth-de\/fund-centre\/ETF\/Gerd-Kommer-Multifactor-Equity\/\" target=\"_blank\" rel=\"noopener\">sito web<\/a> del gestore del fondo L&amp;G. Si prega di leggere questi documenti prima di prendere una decisione d\u2019investimento definitiva. Chi \u00e8 interessato alla struttura tecnica dell&#8217;indice trover\u00e0 tutti i dettagli nella <a href=\"http:\/\/solactive.com\/downloads\/Guideline_SOLGERD.pdf\" target=\"_blank\" rel=\"noopener\">metodologia dell\u2019indice<\/a> (Index Guideline) in lingua inglese.<\/p>\n<p>&nbsp;<\/p>\n<h2><b>Conclusione<\/b><\/h2>\n<p>L&#8217;<em><em>L&amp;G Gerd Kommer Multifactor Equity UCITS ETF<\/em> \u00e8 una soluzione comoda ed efficiente per implementare il concetto di portafoglio globale del Dott. Gerd Kommer in un&#8217;unica soluzione ETF, eventualmente insieme a un deposito bancario fruttifero o a un ETF obbligazionario per rappresentare la parte a basso rischio del portafoglio globale, se lo si desidera.<span class=\"Apple-converted-space\">\u00a0<\/span><\/em><\/p>\n<p>Con il Gerd-Kommer-ETF, l&#8217;investitore si risparmia la ricerca iniziale e la selezione dei singoli ETF e, dopo l&#8217;impostazione iniziale, il lavoro di rebalancing periodico. L&#8217;investitore ha inoltre la certezza che il concetto di portafoglio globale nella variante del factor investing sia stato implementato da esperti.<\/p>\n<p>Con il Gerd-Kommer-ETF \u00e8 possibile iniziare con qualsiasi importo d\u2019investimento e\/o costituire comodamente un patrimonio mensile tramite un piano di accumulo ETF.<\/p>\n<p>&nbsp;<\/p>\n<h2><b>Note finali<\/b><\/h2>\n<p><b>[1]<\/b> &#8220;GBS&#8221; sta per Global Benchmark Series, &#8220;NTR&#8221; per Net Total Return, &#8220;ISIN&#8221; per International Security Identification Number.<\/p>\n<p><b>[2]<\/b>\u00a0Chiunque confronti i rendimenti di fondi o indici diversi deve assicurarsi che la valuta (di solito USD per gli indici, di solito EUR per gli ETF dell&#8217;area euro) sia identica per tutti i dati di rendimento del confronto. Allo stesso modo, \u00e8 necessario assicurarsi che i dividendi siano considerati in modo coerente ovunque (indici total return) e verificare se dai dividendi sono state dedotte eventuali imposte alla fonte (variante dell&#8217;indice di rendimento totale netto rispetto alla variante dell&#8217;indice di rendimento totale lordo). L&#8217;indice Solactive qui menzionato \u00e8 un indice di rendimento totale netto. Gli ETF azionari si riferiscono solitamente a tali indici.<\/p>\n<p><b>[3]<\/b> Il termine &#8220;neutrale rispetto al mercato&#8221; non \u00e8 utilizzato qui nello stesso senso che ha nell&#8217;economia finanziaria accademica, ma nel senso di un orientamento neutrale alla ponderazione delle azioni, che deriva esclusivamente dalla loro capitalizzazione del mercato.<\/p>\n<p><b>[4]<\/b> &#8220;ESG&#8221; sta per <i>Environmental, Social, Governance<\/i> nel contesto dei criteri di sostenibilit\u00e0.<\/p>\n<p><b>[5]<\/b> Ad esempio, sulla base di questo criterio, l\u2019azione Wirecard sarebbe stata esclusa dall&#8217;indice ancor prima del suo crollo definitivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In questo articolo descriviamo la struttura e gli obiettivi dell&#8217;L&amp;G Gerd Kommer Multifactor Equity UCITS ETF.<\/p>\n","protected":false},"author":2,"featured_media":15553,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[102],"tags":[131,128,127,129,130,126],"class_list":["post-17709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-senza-categoria","tag-buy","tag-buy-and-hold","tag-etf","tag-index-fund","tag-passive-investing","tag-stock-market"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L&#039;ETF di Gerd Kommer<\/title>\n<meta name=\"description\" content=\"ETF di Gerd Kommer: Le caratteristiche principali \u2713 Diversificazione, costi e disponibilit\u00e0. \u27a4 Investi ora nell\u2019ETF di Gerd Kommer!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gerd-kommer.de\/it\/blog\/etf-di-gerd-kommer\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;ETF di Gerd Kommer\" \/>\n<meta property=\"og:description\" content=\"ETF di Gerd Kommer: Le caratteristiche principali \u2713 Diversificazione, costi e disponibilit\u00e0. \u27a4 Investi ora nell\u2019ETF di Gerd Kommer!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gerd-kommer.de\/it\/blog\/etf-di-gerd-kommer\/\" \/>\n<meta property=\"og:site_name\" content=\"Gerd Kommer\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gkommer\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-20T22:00:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-17T12:06:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gerd-kommer.de\/medien\/bb-0623.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gerd Kommer\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gerd Kommer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"17 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/blog\\\/etf-di-gerd-kommer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/blog\\\/etf-di-gerd-kommer\\\/\"},\"author\":{\"name\":\"Gerd Kommer\",\"@id\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/#\\\/schema\\\/person\\\/a1ea5059926aae03fce3a1b701bd42b5\"},\"headline\":\"L&#8217;ETF di Gerd Kommer\",\"datePublished\":\"2023-06-20T22:00:56+00:00\",\"dateModified\":\"2025-12-17T12:06:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/blog\\\/etf-di-gerd-kommer\\\/\"},\"wordCount\":2657,\"publisher\":{\"@id\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/blog\\\/etf-di-gerd-kommer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gerd-kommer.de\\\/medien\\\/bb-0623.jpg\",\"keywords\":[\"Buy\",\"Buy and hold\",\"ETF\",\"Index fund\",\"Passive investing\",\"Stock market\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/blog\\\/etf-di-gerd-kommer\\\/\",\"url\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/blog\\\/etf-di-gerd-kommer\\\/\",\"name\":\"L'ETF di Gerd Kommer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/blog\\\/etf-di-gerd-kommer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/blog\\\/etf-di-gerd-kommer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gerd-kommer.de\\\/medien\\\/bb-0623.jpg\",\"datePublished\":\"2023-06-20T22:00:56+00:00\",\"dateModified\":\"2025-12-17T12:06:54+00:00\",\"description\":\"ETF di Gerd Kommer: Le caratteristiche principali \u2713 Diversificazione, costi e disponibilit\u00e0. \u27a4 Investi ora nell\u2019ETF di Gerd Kommer!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/blog\\\/etf-di-gerd-kommer\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/blog\\\/etf-di-gerd-kommer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/blog\\\/etf-di-gerd-kommer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gerd-kommer.de\\\/medien\\\/bb-0623.jpg\",\"contentUrl\":\"https:\\\/\\\/gerd-kommer.de\\\/medien\\\/bb-0623.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Schriftzug \u201eGerd Kommer ETF\u201c mit stilisierter Weltkugel rechts im Bild auf hellem Hintergrund.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/blog\\\/etf-di-gerd-kommer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;ETF di Gerd Kommer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/\",\"name\":\"Gerd Kommer\",\"description\":\"souver\u00e4n investieren mit ETFs\",\"publisher\":{\"@id\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/#organization\",\"name\":\"Gerd Kommer Invest\",\"url\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gerd-kommer.de\\\/medien\\\/gk-logo.png\",\"contentUrl\":\"https:\\\/\\\/gerd-kommer.de\\\/medien\\\/gk-logo.png\",\"width\":2718,\"height\":1030,\"caption\":\"Gerd Kommer Invest\"},\"image\":{\"@id\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/gkommer\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/gerd-kommer-6543158\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/GerdKommer\",\"https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/Gerd_Kommer\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gerd-kommer.de\\\/it\\\/#\\\/schema\\\/person\\\/a1ea5059926aae03fce3a1b701bd42b5\",\"name\":\"Gerd Kommer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ccb710f91a365f94ff3573db5741b4d95541afecab61eb01f7687487eba2b8d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ccb710f91a365f94ff3573db5741b4d95541afecab61eb01f7687487eba2b8d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ccb710f91a365f94ff3573db5741b4d95541afecab61eb01f7687487eba2b8d5?s=96&d=mm&r=g\",\"caption\":\"Gerd Kommer\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L'ETF di Gerd Kommer","description":"ETF di Gerd Kommer: Le caratteristiche principali \u2713 Diversificazione, costi e disponibilit\u00e0. \u27a4 Investi ora nell\u2019ETF di Gerd Kommer!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gerd-kommer.de\/it\/blog\/etf-di-gerd-kommer\/","og_locale":"it_IT","og_type":"article","og_title":"L'ETF di Gerd Kommer","og_description":"ETF di Gerd Kommer: Le caratteristiche principali \u2713 Diversificazione, costi e disponibilit\u00e0. \u27a4 Investi ora nell\u2019ETF di Gerd Kommer!","og_url":"https:\/\/gerd-kommer.de\/it\/blog\/etf-di-gerd-kommer\/","og_site_name":"Gerd Kommer","article_publisher":"https:\/\/www.facebook.com\/gkommer\/","article_published_time":"2023-06-20T22:00:56+00:00","article_modified_time":"2025-12-17T12:06:54+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/gerd-kommer.de\/medien\/bb-0623.jpg","type":"image\/jpeg"}],"author":"Gerd Kommer","twitter_misc":{"Scritto da":"Gerd Kommer","Tempo di lettura stimato":"17 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gerd-kommer.de\/it\/blog\/etf-di-gerd-kommer\/#article","isPartOf":{"@id":"https:\/\/gerd-kommer.de\/it\/blog\/etf-di-gerd-kommer\/"},"author":{"name":"Gerd Kommer","@id":"https:\/\/gerd-kommer.de\/it\/#\/schema\/person\/a1ea5059926aae03fce3a1b701bd42b5"},"headline":"L&#8217;ETF di Gerd Kommer","datePublished":"2023-06-20T22:00:56+00:00","dateModified":"2025-12-17T12:06:54+00:00","mainEntityOfPage":{"@id":"https:\/\/gerd-kommer.de\/it\/blog\/etf-di-gerd-kommer\/"},"wordCount":2657,"publisher":{"@id":"https:\/\/gerd-kommer.de\/it\/#organization"},"image":{"@id":"https:\/\/gerd-kommer.de\/it\/blog\/etf-di-gerd-kommer\/#primaryimage"},"thumbnailUrl":"https:\/\/gerd-kommer.de\/medien\/bb-0623.jpg","keywords":["Buy","Buy and hold","ETF","Index fund","Passive investing","Stock market"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/gerd-kommer.de\/it\/blog\/etf-di-gerd-kommer\/","url":"https:\/\/gerd-kommer.de\/it\/blog\/etf-di-gerd-kommer\/","name":"L'ETF di Gerd Kommer","isPartOf":{"@id":"https:\/\/gerd-kommer.de\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gerd-kommer.de\/it\/blog\/etf-di-gerd-kommer\/#primaryimage"},"image":{"@id":"https:\/\/gerd-kommer.de\/it\/blog\/etf-di-gerd-kommer\/#primaryimage"},"thumbnailUrl":"https:\/\/gerd-kommer.de\/medien\/bb-0623.jpg","datePublished":"2023-06-20T22:00:56+00:00","dateModified":"2025-12-17T12:06:54+00:00","description":"ETF di Gerd Kommer: Le caratteristiche principali \u2713 Diversificazione, costi e disponibilit\u00e0. \u27a4 Investi ora nell\u2019ETF di Gerd Kommer!","breadcrumb":{"@id":"https:\/\/gerd-kommer.de\/it\/blog\/etf-di-gerd-kommer\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gerd-kommer.de\/it\/blog\/etf-di-gerd-kommer\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/gerd-kommer.de\/it\/blog\/etf-di-gerd-kommer\/#primaryimage","url":"https:\/\/gerd-kommer.de\/medien\/bb-0623.jpg","contentUrl":"https:\/\/gerd-kommer.de\/medien\/bb-0623.jpg","width":1200,"height":800,"caption":"Schriftzug \u201eGerd Kommer ETF\u201c mit stilisierter Weltkugel rechts im Bild auf hellem Hintergrund."},{"@type":"BreadcrumbList","@id":"https:\/\/gerd-kommer.de\/it\/blog\/etf-di-gerd-kommer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gerd-kommer.de\/it\/"},{"@type":"ListItem","position":2,"name":"L&#8217;ETF di Gerd Kommer"}]},{"@type":"WebSite","@id":"https:\/\/gerd-kommer.de\/it\/#website","url":"https:\/\/gerd-kommer.de\/it\/","name":"Gerd Kommer","description":"souver\u00e4n investieren mit ETFs","publisher":{"@id":"https:\/\/gerd-kommer.de\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gerd-kommer.de\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/gerd-kommer.de\/it\/#organization","name":"Gerd Kommer Invest","url":"https:\/\/gerd-kommer.de\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/gerd-kommer.de\/it\/#\/schema\/logo\/image\/","url":"https:\/\/gerd-kommer.de\/medien\/gk-logo.png","contentUrl":"https:\/\/gerd-kommer.de\/medien\/gk-logo.png","width":2718,"height":1030,"caption":"Gerd Kommer Invest"},"image":{"@id":"https:\/\/gerd-kommer.de\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/gkommer\/","https:\/\/www.linkedin.com\/in\/gerd-kommer-6543158\/","https:\/\/www.youtube.com\/c\/GerdKommer","https:\/\/de.wikipedia.org\/wiki\/Gerd_Kommer"]},{"@type":"Person","@id":"https:\/\/gerd-kommer.de\/it\/#\/schema\/person\/a1ea5059926aae03fce3a1b701bd42b5","name":"Gerd Kommer","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ccb710f91a365f94ff3573db5741b4d95541afecab61eb01f7687487eba2b8d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ccb710f91a365f94ff3573db5741b4d95541afecab61eb01f7687487eba2b8d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ccb710f91a365f94ff3573db5741b4d95541afecab61eb01f7687487eba2b8d5?s=96&d=mm&r=g","caption":"Gerd Kommer"}}]}},"_links":{"self":[{"href":"https:\/\/gerd-kommer.de\/it\/wp-json\/wp\/v2\/posts\/17709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gerd-kommer.de\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gerd-kommer.de\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gerd-kommer.de\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gerd-kommer.de\/it\/wp-json\/wp\/v2\/comments?post=17709"}],"version-history":[{"count":6,"href":"https:\/\/gerd-kommer.de\/it\/wp-json\/wp\/v2\/posts\/17709\/revisions"}],"predecessor-version":[{"id":20362,"href":"https:\/\/gerd-kommer.de\/it\/wp-json\/wp\/v2\/posts\/17709\/revisions\/20362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gerd-kommer.de\/it\/wp-json\/wp\/v2\/media\/15553"}],"wp:attachment":[{"href":"https:\/\/gerd-kommer.de\/it\/wp-json\/wp\/v2\/media?parent=17709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gerd-kommer.de\/it\/wp-json\/wp\/v2\/categories?post=17709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gerd-kommer.de\/it\/wp-json\/wp\/v2\/tags?post=17709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}